{"id":32,"date":"2008-11-06T16:11:32","date_gmt":"2008-11-06T14:11:32","guid":{"rendered":"https:\/\/celesta.nl\/blog\/celblog\/?p=32"},"modified":"2008-11-06T16:11:32","modified_gmt":"2008-11-06T14:11:32","slug":"testnet-adcampaign-2007schilderijen","status":"publish","type":"post","link":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/","title":{"rendered":"Testnet adcampaign 2007schilderijen"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p><a ?cID=\"13084&amp;sfID=78&amp;afID=99852&amp;ppID=0&amp;sID=29922&amp;style=1\" border=\"0\" src=\"http:\/\/dy.testnet.nl\/serv\/i\/1148\/29922\/13084\/0\/78\/99852_2007schilderijen_250_250.gif\" height=\"250\" width=\"250\" href=\"http:\/\/dy.testnet.nl\/click\/?cID=13084&amp;sfID=78&amp;afID=99852&amp;ppID=0&amp;sID=29922&amp;style=1\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" height=\"250\" width=\"250\" src=\"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428\" align=\"left\" vspace=\"5\" alt=\"2007schilderijen\" hspace=\"5\" title=\"2007schilderijen\" style=\"width: 250px; height: 250px\" \/><\/a>BN&#8217;er in je huis? Unieke schilderijen geschilderd door sterren! Iedere koper steunt het Goede Doel en maakt tevens kans op het originele schilderij, persoonlijk gesigneerd.<br \/>\nDe meesten van jullie hebben vorig jaar ons project 2007schilderijen vanuit de pers wel meegekregen. SBS shownieuws heeft er veel aandacht aan besteed en de radiocommercial is uitgezonden door 100% NL , Skyradio en Radio 10 Gold.<br \/>\nVandaag beginnen we met de advertisingcampagne van Testnet. Webmasters die geinteresseerd zijn, kunnen \u00e9\u00e9n van de banners op hun sites plaatsen en\u00a0\u00a0\u20ac 7,50 per verkocht schilderij verdienen. <a ?cID=\"13084&amp;sfID=61&amp;afID=99850&amp;ppID=0&amp;sID=29922&amp;style=1\" border=\"0\" src=\"http:\/\/dy.testnet.nl\/serv\/i\/1148\/29922\/13084\/0\/61\/99850_2007schilderijen_234_60.gif\" height=\"60\" width=\"234\" href=\"http:\/\/dy.testnet.nl\/click\/?cID=13084&amp;sfID=61&amp;afID=99850&amp;ppID=0&amp;sID=29922&amp;style=1\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" height=\"60\" width=\"234\" src=\"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99850_2007schilderijen_234_60.gif?showme&amp;ts=20080602_104418\" align=\"left\" style=\"width: 234px; height: 60px\" \/><\/a>De timing is ideaal, zo vlak voor de feestdagen. De schilderijen worden vaak als kado gegeven, of mensen kopen een schilderij voor zichzelf natuurlijk.<br \/>\nWebmasters die de ad op hun site willen plaatsen kunnen dit <a href=\"http:\/\/admanager.testnet.nl\/secure\/\" target=\"_blank\" title=\"testnet\">hier<\/a> doen onder dit ID nummer: 13084.<a ?cID=\"13084&amp;sfID=55&amp;afID=99851&amp;ppID=0&amp;sID=29922&amp;style=1\" border=\"0\" src=\"http:\/\/dy.testnet.nl\/serv\/i\/1148\/29922\/13084\/0\/55\/99851_2007schilderijen_468_60.gif\" height=\"60\" width=\"468\" href=\"http:\/\/dy.testnet.nl\/click\/?cID=13084&amp;sfID=55&amp;afID=99851&amp;ppID=0&amp;sID=29922&amp;style=1\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" height=\"60\" width=\"468\" src=\"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99851_2007schilderijen_468_60.gif?showme&amp;ts=20080602_104439\" align=\"left\" style=\"width: 468px; height: 60px\" \/><\/a><\/p>\n<p>Website: <a href=\"http:\/\/www.2007schilderijen.nl\" target=\"_blank\">http:\/\/www.2007schilderijen.nl<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BN&#8217;er in je huis? Unieke schilderijen geschilderd door sterren! Iedere koper steunt het Goede Doel en maakt tevens kans op het originele schilderij, persoonlijk gesigneerd. De meesten van jullie hebben vorig jaar ons project&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32","post","type-post","status-publish","format-standard","hentry","category-whos-gonna-read-this-anyway"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Testnet adcampaign 2007schilderijen - Celesta Surviving Human Nonsense<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Testnet adcampaign 2007schilderijen - Celesta Surviving Human Nonsense\" \/>\n<meta property=\"og:description\" content=\"BN&#8217;er in je huis? Unieke schilderijen geschilderd door sterren! Iedere koper steunt het Goede Doel en maakt tevens kans op het originele schilderij, persoonlijk gesigneerd. De meesten van jullie hebben vorig jaar ons project&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/\" \/>\n<meta property=\"og:site_name\" content=\"Celesta Surviving Human Nonsense\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celesta.vandam\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-06T14:11:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428\" \/>\n<meta name=\"author\" content=\"Celesta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Celesta66\" \/>\n<meta name=\"twitter:site\" content=\"@Celesta66\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Celesta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/\"},\"author\":{\"name\":\"Celesta\",\"@id\":\"https:\\\/\\\/celesta.nl\\\/#\\\/schema\\\/person\\\/3acdffcef9dcd01252bd74d93986f519\"},\"headline\":\"Testnet adcampaign 2007schilderijen\",\"datePublished\":\"2008-11-06T14:11:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/\"},\"wordCount\":134,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dy.testnet.nl\\\/serv\\\/i\\\/1148\\\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428\",\"articleSection\":[\"Who's gonna read this anyway\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/\",\"url\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/\",\"name\":\"Testnet adcampaign 2007schilderijen - Celesta Surviving Human Nonsense\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/celesta.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dy.testnet.nl\\\/serv\\\/i\\\/1148\\\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428\",\"datePublished\":\"2008-11-06T14:11:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/celesta.nl\\\/#\\\/schema\\\/person\\\/3acdffcef9dcd01252bd74d93986f519\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dy.testnet.nl\\\/serv\\\/i\\\/1148\\\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428\",\"contentUrl\":\"http:\\\/\\\/dy.testnet.nl\\\/serv\\\/i\\\/1148\\\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/testnet-adcampaign-2007schilderijen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/celesta.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testnet adcampaign 2007schilderijen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/celesta.nl\\\/#website\",\"url\":\"https:\\\/\\\/celesta.nl\\\/\",\"name\":\"Celesta Surviving Human Nonsense\",\"description\":\"Humor Blogs, Funny Stories and Absurd Observations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/celesta.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/celesta.nl\\\/#\\\/schema\\\/person\\\/3acdffcef9dcd01252bd74d93986f519\",\"name\":\"Celesta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8361a7cbb6a14c18510e2612aaf8d1d55444f0d1ea423982d6ac302cf72c39b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8361a7cbb6a14c18510e2612aaf8d1d55444f0d1ea423982d6ac302cf72c39b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8361a7cbb6a14c18510e2612aaf8d1d55444f0d1ea423982d6ac302cf72c39b6?s=96&d=mm&r=g\",\"caption\":\"Celesta\"},\"sameAs\":[\"https:\\\/\\\/celesta.nl\",\"https:\\\/\\\/x.com\\\/Celesta66\"],\"url\":\"https:\\\/\\\/celesta.nl\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Testnet adcampaign 2007schilderijen - Celesta Surviving Human Nonsense","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/","og_locale":"en_US","og_type":"article","og_title":"Testnet adcampaign 2007schilderijen - Celesta Surviving Human Nonsense","og_description":"BN&#8217;er in je huis? Unieke schilderijen geschilderd door sterren! Iedere koper steunt het Goede Doel en maakt tevens kans op het originele schilderij, persoonlijk gesigneerd. De meesten van jullie hebben vorig jaar ons project&#46;&#46;&#46;","og_url":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/","og_site_name":"Celesta Surviving Human Nonsense","article_publisher":"https:\/\/www.facebook.com\/celesta.vandam","article_published_time":"2008-11-06T14:11:32+00:00","og_image":[{"url":"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428","type":"","width":"","height":""}],"author":"Celesta","twitter_card":"summary_large_image","twitter_creator":"@Celesta66","twitter_site":"@Celesta66","twitter_misc":{"Written by":"Celesta","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/#article","isPartOf":{"@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/"},"author":{"name":"Celesta","@id":"https:\/\/celesta.nl\/#\/schema\/person\/3acdffcef9dcd01252bd74d93986f519"},"headline":"Testnet adcampaign 2007schilderijen","datePublished":"2008-11-06T14:11:32+00:00","mainEntityOfPage":{"@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/"},"wordCount":134,"commentCount":5,"image":{"@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/#primaryimage"},"thumbnailUrl":"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428","articleSection":["Who's gonna read this anyway"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/","url":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/","name":"Testnet adcampaign 2007schilderijen - Celesta Surviving Human Nonsense","isPartOf":{"@id":"https:\/\/celesta.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/#primaryimage"},"image":{"@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/#primaryimage"},"thumbnailUrl":"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428","datePublished":"2008-11-06T14:11:32+00:00","author":{"@id":"https:\/\/celesta.nl\/#\/schema\/person\/3acdffcef9dcd01252bd74d93986f519"},"breadcrumb":{"@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/#primaryimage","url":"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428","contentUrl":"http:\/\/dy.testnet.nl\/serv\/i\/1148\/99852_2007schilderijen_250_250.gif?showme&amp;ts=20080602_104428"},{"@type":"BreadcrumbList","@id":"https:\/\/celesta.nl\/index.php\/testnet-adcampaign-2007schilderijen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/celesta.nl\/"},{"@type":"ListItem","position":2,"name":"Testnet adcampaign 2007schilderijen"}]},{"@type":"WebSite","@id":"https:\/\/celesta.nl\/#website","url":"https:\/\/celesta.nl\/","name":"Celesta Surviving Human Nonsense","description":"Humor Blogs, Funny Stories and Absurd Observations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/celesta.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/celesta.nl\/#\/schema\/person\/3acdffcef9dcd01252bd74d93986f519","name":"Celesta","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8361a7cbb6a14c18510e2612aaf8d1d55444f0d1ea423982d6ac302cf72c39b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8361a7cbb6a14c18510e2612aaf8d1d55444f0d1ea423982d6ac302cf72c39b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8361a7cbb6a14c18510e2612aaf8d1d55444f0d1ea423982d6ac302cf72c39b6?s=96&d=mm&r=g","caption":"Celesta"},"sameAs":["https:\/\/celesta.nl","https:\/\/x.com\/Celesta66"],"url":"https:\/\/celesta.nl\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/posts\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":0,"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/posts\/32\/revisions"}],"wp:attachment":[{"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/media?parent=32"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/categories?post=32"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celesta.nl\/index.php\/wp-json\/wp\/v2\/tags?post=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}